{"id":1965,"date":"2014-12-05T13:12:26","date_gmt":"2014-12-05T12:12:26","guid":{"rendered":"http:\/\/aktuelles.uni-frankfurt.de\/?p=1965"},"modified":"2016-01-10T22:01:16","modified_gmt":"2016-01-10T21:01:16","slug":"komplexe-atmosphaere","status":"publish","type":"post","link":"https:\/\/aktuelles.uni-frankfurt.de\/en\/forschung\/komplexe-atmosphaere\/","title":{"rendered":"Komplexe Atmosph\u00e4re"},"content":{"rendered":"<figure id=\"attachment_1966\" aria-describedby=\"caption-attachment-1966\" style=\"width: 700px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-1966 size-full\" src=\"https:\/\/aktuelles.uni-frankfurt.de\/wp-content\/uploads\/2015\/12\/blog_unireport_atmosphaere.jpg\" alt=\"Das \u201eCLOUD-Experiment\u201c in der Kernforschungseinrichtung CERN (Oktober 2013); Foto: \u00a9 CERN\" width=\"700\" height=\"466\" srcset=\"https:\/\/aktuelles.uni-frankfurt.de\/wp-content\/uploads\/2015\/12\/blog_unireport_atmosphaere.jpg 700w, https:\/\/aktuelles.uni-frankfurt.de\/wp-content\/uploads\/2015\/12\/blog_unireport_atmosphaere-300x200.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-1966\" class=\"wp-caption-text\">Das \u201eCLOUD-Experiment\u201c in der Kernforschungseinrichtung CERN (Oktober 2013); Foto: \u00a9 CERN<\/figcaption><\/figure>\n<p>Wasser, Schwefels\u00e4ure, und damit hat sich\u2019s \u2013 davon gingen Atmosph\u00e4renforscher fr\u00fcher aus. Aber der Kreis der Verd\u00e4chtigen hat sich deutlich erweitert: \u201eVor ein paar Jahren dachte man, Wolken entstehen in der Atmosph\u00e4re, wenn Wassermolek\u00fcle auf Partikel aus Sulfat treffen und zu Fl\u00fcssigkeit kondensieren, und dass ein gro\u00dfer Teil dieser Sulfatpartikel sich in der Atmosph\u00e4re neu gebildet hat, indem Schwefels\u00e4ure und Wassermolek\u00fcle sich zusammenlagern.<\/p>\n<p>Heute wissen wir, dass das Szenario viel komplexer ist\u201c, sagt Joachim Curtius, Professor f\u00fcr experimentelle Atmosph\u00e4renforschung an der Goethe-Universit\u00e4t. Er z\u00e4hlt auf: \u201eIn der Atmosph\u00e4re wurden auch Molek\u00fclanh\u00e4ufungen, so genannte Cluster, aus verschiedenen organischen Substanzen als Kondensationskeime nachgewiesen.\u201c Wissenschaftler aus seiner Arbeitsgruppe haben zusammen mit einem internationalen Forscherteam jetzt in einem Laborexperiment nachgewiesen, dass das Clusterwachstum entscheidend erleichtert wird, wenn nicht nur Schwefels\u00e4ure-, sondern zugleich Dimethylamin (DMA)-Molek\u00fcle in die Cluster eingebaut werden.<\/p>\n<h3>\u00bbSuperklebstoff\u00ab f\u00fcr die Atmosph\u00e4re<\/h3>\n<p>In einem Beitrag f\u00fcr die amerikanische Fachzeitschrift \u201eProceedings of the National Academy of Sciences\u201c berichten die Wissenschaftler um Curtius zun\u00e4chst, wie sie ein bew\u00e4hrtes Messverfahren in einem wesentlichen Punkt weiterentwickelt haben: Dieses Messverfahren, ein spezielles Massenspektrometer, eignet sich n\u00e4mlich f\u00fcr den Nachweis elektrisch geladener Teilchen. Im unteren Teil der Atmosph\u00e4re, wo Wolken entstehen, kommt es aber vor allem auf neutrale (ungeladene) Cluster an.<\/p>\n<p>Der Trick von Curtius und seinen Mitarbeitern bestand darin, dass sie diese neutralen Cluster mit Hilfe einer eigens daf\u00fcr entwickelten Ionenquelle in geladene Teilchen umwandelten; anschlie\u00dfend konnten sie Gr\u00f6\u00dfe und Zusammensetzung der urspr\u00fcnglich neutralen Cluster bestimmen. Mit dem neuen Messverfahren konnten die Forscher das Cluster-Wachstum direkt beobachten \u2013 und sie stellten fest, dass das Wachstum in Anwesenheit von DMA extrem beg\u00fcnstigt ist:<\/p>\n<p>W\u00e4hrend Cluster, die nur aus Schwefels\u00e4ure bestehen, erst von einer bestimmten Mindestgr\u00f6\u00dfe an stabil sind, bestand diese Barriere nicht, wenn zus\u00e4tzlich DMA-Molek\u00fcle in die Cluster eingebaut wurden. \u201eDas bedeutet: Wenn DMA beteiligt ist, bleibt jedes weitere Schwefels\u00e4ure-Molek\u00fcl, das mit dem Cluster zusammenst\u00f6\u00dft, daran kleben und vergr\u00f6\u00dfert das Cluster\u201c, erl\u00e4utert Curtius. \u201eWir haben unser Experiment am CERN in Genf gemacht, und zwar unter Bedingungen, wie sie tats\u00e4chlich in der Atmosph\u00e4re herrschen.<\/p>\n<p>Das hei\u00dft vor allem: Die Konzentrationen an Schwefels\u00e4ure und DMA waren extrem gering. Nur eines von tausend Milliarden Teilchen war ein DMA- oder Schwefels\u00e4uremolek\u00fcl, da ist es entscheidend, dass die Molek\u00fcle aneinander kleben bleiben und nicht wieder auseinanderfliegen, wenn sie sich schon mal treffen.\u201c DMA entsteht in der Landwirtschaft, gasf\u00f6rmige Schwefels\u00e4ure entsteht aus Schwefeldioxid, das beispielsweise bei der Verbrennung fossiler Materialien gebildet wird.<\/p>\n<p>Ihr Zusammenwirken wurde zwar unter atmosph\u00e4rischen Bedingungen, aber eben doch nur im Laborexperiment am Boden nachgewiesen. Allerdings k\u00f6nnte das Forschungsflugzeug HALO (High Altitude and LOng Range Research Aircraft) dazu beitragen, dass aufgekl\u00e4rt wird, welche Vorg\u00e4nge tats\u00e4chlich bei der Partikelneubildung in der Atmosph\u00e4re ablaufen. HALO wird vom Deutschen Zentrum f\u00fcr Luft- und Raumfahrt (DLR) betrieben, verschiedene Forschungsinstitutionen nutzen es gemeinsam, und Curtius koordiniert zusammen mit Forschern aus Leipzig und Dresden das HALO-Forschungsprogramm der DFG.<\/p>\n<p>Die j\u00fcngste HALO-Messkampagne f\u00fchrte ins brasilianische Amazonasgebiet, wo die Entstehung und Entwicklung tropischer Gewitterwolken untersucht wurde. \u201eZur Partikelneubildung sind aktuell keine HALO-Messungen geplant\u201c, schr\u00e4nkt Curtius ein, \u201eaber wir w\u00fcrden uns einen gro\u00dfen Erkenntnisgewinn davon erhoffen, wenn wir sie eines Tages durchf\u00fchren k\u00f6nnten. Wir vermuten, dass auch in der freien Troposph\u00e4re, also in einer H\u00f6he oberhalb von zwei Kilometern, Cluster entstehen und neue Partikel gebildet werden, allerdings dort eher aus Schwefels\u00e4ure, Ammoniak und Wasser, da das DMA nur nahe an den Quellen am Boden vorkommt.<\/p>\n<p>In jedem Fall interessiert uns, inwieweit die Partikelkonzentrationen in der Atmosph\u00e4re durch die Neubildung beeinflusst werden. Das kann gro\u00dfen Einfluss auf die Struktur und das Reflexionsverhalten von Wolken haben und wirkt sich somit auf unser Klima aus.\u201c<\/p>\n<h3>DFG-Forschergruppe zu Schwerewellen<\/h3>\n<p>2016 wird HALO im Auftrag des DLR abheben und dabei auch Messungen zu so genannten Schwerewellen ausf\u00fchren. Mit diesen Schwerewellen wird sich eine Forschergruppe unter Federf\u00fchrung der Goethe-Universit\u00e4t befassen, die von der DFG k\u00fcrzlich eingerichtet wurde. Daran beteiligt sind noch zehn weitere deutsche Institutionen, so etwa die Universit\u00e4t Mainz, das Max-Planck-Institut f\u00fcr Meteorologie in Hamburg, das DLR bei M\u00fcnchen und der Deutsche Wetterdienst (DWD) in Offenbach.<\/p>\n<p>In den n\u00e4chsten drei Jahren planen die Wissenschaftler Laborexperimente und Messkampagnen; au\u00dferdem sollen Theorien entwickelt und Computersimulationen berechnet werden. Sprecher der neuen DFG-Forschergruppe ist Ulrich Achatz, Professor f\u00fcr theoretische Atmosph\u00e4renforschung an der Goethe-Universit\u00e4t. Er erl\u00e4utert: \u201eSchwerewellen entstehen aus dem Wechselspiel von Schwerkraft und Druckgradientenkraft: Weiter unten, also n\u00e4her an der Erdoberfl\u00e4che, ist der Luftdruck gr\u00f6\u00dfer.<\/p>\n<p>Das treibt die Luftpakete nach oben, und die Luft k\u00fchlt sich ab. Hat ein Luftpaket eine H\u00f6he erreicht, in der es dichter und schwerer als seine Umgebung ist, wird es durch die Schwerkraft wieder nach unten gezogen, und die Luft erw\u00e4rmt sich wieder.\u201c Auf diese Weise best\u00fcnden Schwerewellen abwechselnd aus Bereichen absinkender und aufsteigender Luft, charakterisiert durch periodische Ver\u00e4nderungen von Windgeschwindigkeit, Druck, Dichte und Temperatur.<\/p>\n<h3>Nordwind in Frankfurt<\/h3>\n<p>Achatz nennt ein Beispiel, das Frankfurtern vertraut sein d\u00fcrfte: \u201eWenn der Wind in Frankfurt aus Norden kommt, streichen die Luftmassen \u00fcber den Taunus hinweg. Dabei entstehen Schwerewellen, und wenn die Luft in diesen Schwerewellen aufsteigt und absinkt, ist das an den Wolkenb\u00e4ndern sichtbar, die dann beispielweise \u00fcber Niederursel oder dem Riedberg auftauchen.\u201c<\/p>\n<p>Schwerewellen entstehen aber nicht nur, wenn Luftmassen Gebirge \u00fcberstr\u00f6men, sondern auch in Gewittern, weil diese stets mit einem vertikalen Lufttransport verbunden sind \u2013 das ist beispielsweise erkennbar an den charakteristischen, ambossf\u00f6rmigen \u201eCumulonimbuswolken\u201c, die sich oft kilometerhoch auft\u00fcrmen, wenn ein Gewitter ,in der Luft liegt\u2018. Schlie\u00dflich werden Schwerewellen von den Hoch- und Tiefdruckgebieten abgestrahlt. Achatz erkl\u00e4rt dazu: \u201eSchon von der Wetterkarte her kennen wir die Tatsache, dass sich Luft um die Hoch- und Tiefdruckgebiete herum bewegt, entlang den Linien konstanten Drucks.<\/p>\n<p>Einerseits werden n\u00e4mlich die Luftmolek\u00fcle vom hohen zum niedrigen Luftdruck getrieben, und andererseits wird diese Bewegung durch die Erdrotation beeinflusst. Den daraus resultierenden Zustand, in dem sich die Luft entlang der Isobaren bewegt, strebt die Natur mit Macht an. Wenn das \u00e4u\u00dferst komplexe System der Atmosph\u00e4re dieses Gleichgewicht verl\u00e4sst, etwa durch ,\u00dcberschie\u00dfen\u2018 der eigenen Dynamik, dann versucht sie, diesen Zustand wieder herzustellen, indem Schwerewellen abgestrahlt werden.<\/p>\n<p>Viele der Ursachen f\u00fcr Schwerewellen sind erst unzureichend verstanden \u2013 ihre Auswirkungen auf Wetter und Klima aber noch weniger. Ein Hauptproblem: Die Datenpunkte, an denen beispielsweise der DWD mit seinen Modellen die konkreten Vorhersagewerte berechnet, liegen so weit auseinander, dass sich in einer Schwerewelle die vertikale Luftbewegung zwischen den Punkten mehrmals umkehrt. Das hei\u00dft, dass Wettermodelle diesen Wechsel zwischen Aufsteigen und Absinken ignorieren, obwohl sein Einfluss auf das Wetter in Wirklichkeit dramatisch sein kann.<\/p>\n<p>Und manchmal geht es nicht nur darum, in den n\u00e4chsten Tagen das Wetter beispielsweise im Rhein-Main-Gebiet vorherzusagen, sondern es werden gr\u00f6\u00dfere Gebiete betrachtet, oder es geht um Klimamodelle, die die Entwicklung im Laufe der Jahrzehnte, Jahrhunderte beschreiben \u2013 dann liegen die Datenpunkte noch wesentlich weiter auseinander. Achatz\u2019 Ziel ist es also, im Rahmen der neuen DFG-Forschergruppe einen Baustein f\u00fcr Wetter- und Klimamodelle zu entwickeln, eine sogenannte Parametrisierung, die den Benutzern eines Modells angibt, wie sich die Schwerewellen auf Wetter und Klima auswirken, obwohl sie sich auf so kleinen Gebieten abspielen, dass sie f\u00fcr das Modell nicht \u201esichtbar\u201c sind.<\/p>\n<p>Au\u00dferdem streben die Atmosph\u00e4renforscher der Goethe-Universit\u00e4t an, die Zusammenarbeit mit dem DWD weiter zu vertiefen und verst\u00e4rkt die Meteorologie der unteren ein bis zwei Kilometer, der \u201eatmosph\u00e4rischen Grenzschicht\u201c, zu erforschen. Auch davon erhoffen sie eine bessere Modellierung von Wetter und Klima. <em>[Autorin: Stefanie Hense]<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wasser, Schwefels\u00e4ure, und damit hat sich\u2019s \u2013 davon gingen Atmosph\u00e4renforscher fr\u00fcher aus. Aber der Kreis der Verd\u00e4chtigen hat sich deutlich erweitert: \u201eVor ein paar Jahren dachte man, Wolken entstehen in [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":1966,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[3],"tags":[10],"post_folder":[],"class_list":["post-1965","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forschung","tag-unireport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Komplexe Atmosph\u00e4re | Aktuelles aus der Goethe-Universit\u00e4t Frankfurt<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aktuelles.uni-frankfurt.de\/en\/forschung\/komplexe-atmosphaere\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Komplexe Atmosph\u00e4re | Aktuelles aus der Goethe-Universit\u00e4t Frankfurt\" \/>\n<meta property=\"og:description\" content=\"Wasser, Schwefels\u00e4ure, und damit hat sich\u2019s \u2013 davon gingen Atmosph\u00e4renforscher fr\u00fcher aus. Aber der Kreis der Verd\u00e4chtigen hat sich deutlich erweitert: \u201eVor ein paar Jahren dachte man, Wolken entstehen in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aktuelles.uni-frankfurt.de\/en\/forschung\/komplexe-atmosphaere\/\" \/>\n<meta property=\"og:site_name\" content=\"Aktuelles aus der Goethe-Universit\u00e4t Frankfurt\" \/>\n<meta property=\"article:published_time\" content=\"2014-12-05T12:12:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-10T21:01:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aktuelles.uni-frankfurt.de\/wp-content\/uploads\/2015\/12\/blog_unireport_atmosphaere.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"466\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"-\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"-\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/forschung\\\/komplexe-atmosphaere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/forschung\\\/komplexe-atmosphaere\\\/\"},\"author\":{\"name\":\"-\",\"@id\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/#\\\/schema\\\/person\\\/8e55ea338fb65d1ce87a91565d1f1739\"},\"headline\":\"Komplexe Atmosph\u00e4re\",\"datePublished\":\"2014-12-05T12:12:26+00:00\",\"dateModified\":\"2016-01-10T21:01:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/forschung\\\/komplexe-atmosphaere\\\/\"},\"wordCount\":1328,\"publisher\":{\"@id\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/forschung\\\/komplexe-atmosphaere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/blog_unireport_atmosphaere.jpg\",\"keywords\":[\"UniReport\"],\"articleSection\":[\"Forschung\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/forschung\\\/komplexe-atmosphaere\\\/\",\"url\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/forschung\\\/komplexe-atmosphaere\\\/\",\"name\":\"Komplexe Atmosph\u00e4re | Aktuelles aus der Goethe-Universit\u00e4t Frankfurt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/forschung\\\/komplexe-atmosphaere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/forschung\\\/komplexe-atmosphaere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/blog_unireport_atmosphaere.jpg\",\"datePublished\":\"2014-12-05T12:12:26+00:00\",\"dateModified\":\"2016-01-10T21:01:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/forschung\\\/komplexe-atmosphaere\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/forschung\\\/komplexe-atmosphaere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/forschung\\\/komplexe-atmosphaere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/blog_unireport_atmosphaere.jpg\",\"contentUrl\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/blog_unireport_atmosphaere.jpg\",\"width\":700,\"height\":466,\"caption\":\"Das \u201eCLOUD-Experiment\u201c in der Kernforschungseinrichtung CERN (Oktober 2013); Foto: \u00a9 CERN\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/forschung\\\/komplexe-atmosphaere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Komplexe Atmosph\u00e4re\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/#website\",\"url\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/\",\"name\":\"Aktuelles aus der Goethe-Universit\u00e4t Frankfurt\",\"description\":\"Aktuelles aus der Goethe-Universit\u00e4t | Neues aus Forschung, Lehre, Studium\",\"publisher\":{\"@id\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/#organization\",\"name\":\"Goethe-Universit\u00e4t\",\"url\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/800px-Goethe-Logo.png\",\"contentUrl\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/800px-Goethe-Logo.png\",\"width\":800,\"height\":436,\"caption\":\"Goethe-Universit\u00e4t\"},\"image\":{\"@id\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/#\\\/schema\\\/person\\\/8e55ea338fb65d1ce87a91565d1f1739\",\"name\":\"-\",\"description\":\"Dieser Beitrag wurde von der Online-Redaktion ver\u00f6ffentlicht. Wenn der Beitrag von einem Gastautoren verfasst wurde, findet sich dieser Hinweis am Ende des jeweiligen Artikels.\",\"sameAs\":[\"http:\\\/\\\/aktuelles.uni-frankfurt.de\\\/autoren\"],\"url\":\"https:\\\/\\\/aktuelles.uni-frankfurt.de\\\/en\\\/author\\\/redaktion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Komplexe Atmosph\u00e4re | Aktuelles aus der Goethe-Universit\u00e4t Frankfurt","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aktuelles.uni-frankfurt.de\/en\/forschung\/komplexe-atmosphaere\/","og_locale":"en_GB","og_type":"article","og_title":"Komplexe Atmosph\u00e4re | Aktuelles aus der Goethe-Universit\u00e4t Frankfurt","og_description":"Wasser, Schwefels\u00e4ure, und damit hat sich\u2019s \u2013 davon gingen Atmosph\u00e4renforscher fr\u00fcher aus. Aber der Kreis der Verd\u00e4chtigen hat sich deutlich erweitert: \u201eVor ein paar Jahren dachte man, Wolken entstehen in [&hellip;]","og_url":"https:\/\/aktuelles.uni-frankfurt.de\/en\/forschung\/komplexe-atmosphaere\/","og_site_name":"Aktuelles aus der Goethe-Universit\u00e4t Frankfurt","article_published_time":"2014-12-05T12:12:26+00:00","article_modified_time":"2016-01-10T21:01:16+00:00","og_image":[{"width":700,"height":466,"url":"https:\/\/aktuelles.uni-frankfurt.de\/wp-content\/uploads\/2015\/12\/blog_unireport_atmosphaere.jpg","type":"image\/jpeg"}],"author":"-","twitter_card":"summary_large_image","twitter_misc":{"Written by":"-","Estimated reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aktuelles.uni-frankfurt.de\/forschung\/komplexe-atmosphaere\/#article","isPartOf":{"@id":"https:\/\/aktuelles.uni-frankfurt.de\/forschung\/komplexe-atmosphaere\/"},"author":{"name":"-","@id":"https:\/\/aktuelles.uni-frankfurt.de\/#\/schema\/person\/8e55ea338fb65d1ce87a91565d1f1739"},"headline":"Komplexe Atmosph\u00e4re","datePublished":"2014-12-05T12:12:26+00:00","dateModified":"2016-01-10T21:01:16+00:00","mainEntityOfPage":{"@id":"https:\/\/aktuelles.uni-frankfurt.de\/forschung\/komplexe-atmosphaere\/"},"wordCount":1328,"publisher":{"@id":"https:\/\/aktuelles.uni-frankfurt.de\/#organization"},"image":{"@id":"https:\/\/aktuelles.uni-frankfurt.de\/forschung\/komplexe-atmosphaere\/#primaryimage"},"thumbnailUrl":"https:\/\/aktuelles.uni-frankfurt.de\/wp-content\/uploads\/2015\/12\/blog_unireport_atmosphaere.jpg","keywords":["UniReport"],"articleSection":["Forschung"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/aktuelles.uni-frankfurt.de\/forschung\/komplexe-atmosphaere\/","url":"https:\/\/aktuelles.uni-frankfurt.de\/forschung\/komplexe-atmosphaere\/","name":"Komplexe Atmosph\u00e4re | Aktuelles aus der Goethe-Universit\u00e4t Frankfurt","isPartOf":{"@id":"https:\/\/aktuelles.uni-frankfurt.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aktuelles.uni-frankfurt.de\/forschung\/komplexe-atmosphaere\/#primaryimage"},"image":{"@id":"https:\/\/aktuelles.uni-frankfurt.de\/forschung\/komplexe-atmosphaere\/#primaryimage"},"thumbnailUrl":"https:\/\/aktuelles.uni-frankfurt.de\/wp-content\/uploads\/2015\/12\/blog_unireport_atmosphaere.jpg","datePublished":"2014-12-05T12:12:26+00:00","dateModified":"2016-01-10T21:01:16+00:00","breadcrumb":{"@id":"https:\/\/aktuelles.uni-frankfurt.de\/forschung\/komplexe-atmosphaere\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aktuelles.uni-frankfurt.de\/forschung\/komplexe-atmosphaere\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/aktuelles.uni-frankfurt.de\/forschung\/komplexe-atmosphaere\/#primaryimage","url":"https:\/\/aktuelles.uni-frankfurt.de\/wp-content\/uploads\/2015\/12\/blog_unireport_atmosphaere.jpg","contentUrl":"https:\/\/aktuelles.uni-frankfurt.de\/wp-content\/uploads\/2015\/12\/blog_unireport_atmosphaere.jpg","width":700,"height":466,"caption":"Das \u201eCLOUD-Experiment\u201c in der Kernforschungseinrichtung CERN (Oktober 2013); Foto: \u00a9 CERN"},{"@type":"BreadcrumbList","@id":"https:\/\/aktuelles.uni-frankfurt.de\/forschung\/komplexe-atmosphaere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/aktuelles.uni-frankfurt.de\/"},{"@type":"ListItem","position":2,"name":"Komplexe Atmosph\u00e4re"}]},{"@type":"WebSite","@id":"https:\/\/aktuelles.uni-frankfurt.de\/#website","url":"https:\/\/aktuelles.uni-frankfurt.de\/","name":"Aktuelles aus der Goethe-Universit\u00e4t Frankfurt","description":"Aktuelles aus der Goethe-Universit\u00e4t | Neues aus Forschung, Lehre, Studium","publisher":{"@id":"https:\/\/aktuelles.uni-frankfurt.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aktuelles.uni-frankfurt.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/aktuelles.uni-frankfurt.de\/#organization","name":"Goethe University Frankfurt","url":"https:\/\/aktuelles.uni-frankfurt.de\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/aktuelles.uni-frankfurt.de\/#\/schema\/logo\/image\/","url":"https:\/\/aktuelles.uni-frankfurt.de\/wp-content\/uploads\/2022\/03\/800px-Goethe-Logo.png","contentUrl":"https:\/\/aktuelles.uni-frankfurt.de\/wp-content\/uploads\/2022\/03\/800px-Goethe-Logo.png","width":800,"height":436,"caption":"Goethe-Universit\u00e4t"},"image":{"@id":"https:\/\/aktuelles.uni-frankfurt.de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/aktuelles.uni-frankfurt.de\/#\/schema\/person\/8e55ea338fb65d1ce87a91565d1f1739","name":"-","description":"Dieser Beitrag wurde von der Online-Redaktion ver\u00f6ffentlicht. Wenn der Beitrag von einem Gastautoren verfasst wurde, findet sich dieser Hinweis am Ende des jeweiligen Artikels.","sameAs":["http:\/\/aktuelles.uni-frankfurt.de\/autoren"],"url":"https:\/\/aktuelles.uni-frankfurt.de\/en\/author\/redaktion\/"}]}},"_links":{"self":[{"href":"https:\/\/aktuelles.uni-frankfurt.de\/en\/wp-json\/wp\/v2\/posts\/1965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aktuelles.uni-frankfurt.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aktuelles.uni-frankfurt.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aktuelles.uni-frankfurt.de\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/aktuelles.uni-frankfurt.de\/en\/wp-json\/wp\/v2\/comments?post=1965"}],"version-history":[{"count":0,"href":"https:\/\/aktuelles.uni-frankfurt.de\/en\/wp-json\/wp\/v2\/posts\/1965\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aktuelles.uni-frankfurt.de\/en\/wp-json\/wp\/v2\/media\/1966"}],"wp:attachment":[{"href":"https:\/\/aktuelles.uni-frankfurt.de\/en\/wp-json\/wp\/v2\/media?parent=1965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aktuelles.uni-frankfurt.de\/en\/wp-json\/wp\/v2\/categories?post=1965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aktuelles.uni-frankfurt.de\/en\/wp-json\/wp\/v2\/tags?post=1965"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/aktuelles.uni-frankfurt.de\/en\/wp-json\/wp\/v2\/post_folder?post=1965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}